{"id":318,"date":"2009-11-18T13:53:00","date_gmt":"2009-11-18T05:53:00","guid":{"rendered":"https:\/\/villaseran.com\/rom\/?p=318"},"modified":"2022-11-18T13:54:53","modified_gmt":"2022-11-18T05:54:53","slug":"matadora-wing-piece-ii","status":"publish","type":"post","link":"https:\/\/villaseran.com\/rom\/paintings\/matadora-wing-piece-ii\/","title":{"rendered":"Matadora Wing Piece II"},"content":{"rendered":"\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/villaseran.com\/rom\/wp-content\/uploads\/2022\/11\/MATADORA-WING-PIECE-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"790\" height=\"720\" src=\"https:\/\/villaseran.com\/rom\/wp-content\/uploads\/2022\/11\/MATADORA-WING-PIECE-2.jpg\" alt=\"\" class=\"wp-image-319\" srcset=\"https:\/\/villaseran.com\/rom\/wp-content\/uploads\/2022\/11\/MATADORA-WING-PIECE-2.jpg 790w, https:\/\/villaseran.com\/rom\/wp-content\/uploads\/2022\/11\/MATADORA-WING-PIECE-2-329x300.jpg 329w, https:\/\/villaseran.com\/rom\/wp-content\/uploads\/2022\/11\/MATADORA-WING-PIECE-2-768x700.jpg 768w\" sizes=\"auto, (max-width: 790px) 100vw, 790px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>acrylic on canvas<br \/>\n91.44 x 91.44 cm<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","footnotes":""},"categories":[6],"tags":[],"class_list":["post-318","post","type-post","status-publish","format-standard","hentry","category-paintings"],"_links":{"self":[{"href":"https:\/\/villaseran.com\/rom\/wp-json\/wp\/v2\/posts\/318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/villaseran.com\/rom\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/villaseran.com\/rom\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/villaseran.com\/rom\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/villaseran.com\/rom\/wp-json\/wp\/v2\/comments?post=318"}],"version-history":[{"count":1,"href":"https:\/\/villaseran.com\/rom\/wp-json\/wp\/v2\/posts\/318\/revisions"}],"predecessor-version":[{"id":320,"href":"https:\/\/villaseran.com\/rom\/wp-json\/wp\/v2\/posts\/318\/revisions\/320"}],"wp:attachment":[{"href":"https:\/\/villaseran.com\/rom\/wp-json\/wp\/v2\/media?parent=318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/villaseran.com\/rom\/wp-json\/wp\/v2\/categories?post=318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/villaseran.com\/rom\/wp-json\/wp\/v2\/tags?post=318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}